{"id":1918,"date":"2022-01-05T13:57:32","date_gmt":"2022-01-05T12:57:32","guid":{"rendered":"https:\/\/www.panoramahotel.de\/wellness-intro\/wellness\/"},"modified":"2025-02-20T09:48:42","modified_gmt":"2025-02-20T08:48:42","slug":"wellness","status":"publish","type":"page","link":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/","title":{"rendered":"Wellness"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_5 1_5 fusion-one-fifth fusion-column-first\" style=\"--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"500\" height=\"326\" title=\"Logo_Spanorama\" src=\"http:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/Logo_Spanorama.png\" alt class=\"img-responsive wp-image-1529\" srcset=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/Logo_Spanorama-200x130.png 200w, https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/Logo_Spanorama-400x261.png 400w, https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/Logo_Spanorama.png 500w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_4_5 4_5 fusion-four-fifth fusion-column-last\" style=\"--awb-bg-size:cover;width:80%;width:calc(80% - ( ( 4% ) * 0.8 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Here, time and tranquillity for relaxation become tangible<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\" style=\"--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Treat yourself to a well-deserved break. In our wellness area you can unwind, relax and enjoy the fantastic panorama.<\/p>\n<p>Take a few leisurely laps in our indoor pool or get active with the counter-current system. Afterwards you can let yourself be pampered with a massage by trained hands in the &#8220;Aloha Nani&#8221; relaxation studio.<\/p>\n<h3><strong>There are numerous highlights to discover here:<\/strong><\/h3>\n<\/div><ul style=\"--awb-margin-bottom:35px;--awb-iconcolor:#d30606;--awb-line-height:23.8px;--awb-icon-width:23.8px;--awb-icon-height:23.8px;--awb-icon-margin:9.8px;--awb-content-margin:33.6px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Finnish sauna<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Tecaldarium<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Steam bath<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Physiotherm infrared cabin<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Experience shower with tropical rain and Kneipp hose<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Heated bench with footbath<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Cozy moorings<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Fantastic PANORAMA view<\/p>\n<\/div><\/li><\/ul><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-bottom:10px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Opening hours:<\/h3><\/div><div class=\"fusion-text fusion-text-2\">\n<table id=\"tablepress-36\" class=\"tablepress tablepress-id-36\">\n<tbody class=\"row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Hallenbad mit Gegenstromanlage<\/td><td class=\"column-2\">07:30<\/td><td class=\"column-3\">bis<\/td><td class=\"column-4\">21:00 Uhr<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Finnische Sauna, Dampfbad<\/td><td class=\"column-2\">13:30<\/td><td class=\"column-3\">bis<\/td><td class=\"column-4\">21:00 Uhr<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last fusion-animated\" style=\"--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );\" data-animationType=\"slideInUp\" data-animationDuration=\"0.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\"><div style=\"margin:-2px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-14 fusion-gallery-layout-grid fusion-gallery-1\"><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8413_900x600px.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8413_900x600px-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"wellness_DEX_8413_900x600px\" aria-label=\"wellness_DEX_8413_900x600px\" class=\"img-responsive wp-image-669 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8453_900x600px.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8453_900x600px-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"wellness_DEX_8453_900x600px\" aria-label=\"wellness_DEX_8453_900x600px\" class=\"img-responsive wp-image-670 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8406_900x600px.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/10\/wellness_DEX_8406_900x600px-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"wellness_DEX_8406_900x600px\" aria-label=\"wellness_DEX_8406_900x600px\" class=\"img-responsive wp-image-668 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_01.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_01-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-275 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_02.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_02-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-276 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_03.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_03-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-277 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_04.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_04-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-278 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_05.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_05-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-279 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_06.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_06-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-280 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_07.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_07-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-281 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_08.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_08-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-282 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_09.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_09-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-283 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_10.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_10-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-284 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:2.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_11.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/wellness_11-460x295.jpg\" width=\"460\" height=\"295\" alt=\"\" title=\"Ansicht Wellnessbereich\" aria-label=\"Ansicht Wellnessbereich\" class=\"img-responsive wp-image-285 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1911,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-1918","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wellness - PANORAMA Hotel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wellness - PANORAMA Hotel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/\" \/>\n<meta property=\"og:site_name\" content=\"PANORAMA Hotel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PANORAMA.Hotel.Heimbuchenthal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T08:48:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/wellness\\\/\",\"url\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/wellness\\\/\",\"name\":\"Wellness - PANORAMA Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#website\"},\"datePublished\":\"2022-01-05T12:57:32+00:00\",\"dateModified\":\"2025-02-20T08:48:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/wellness\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/wellness\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/wellness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wellness-Intro\",\"item\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/wellness-intro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wellness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/\",\"name\":\"PANORAMA Hotel\",\"description\":\"Heimbuchenthal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#organization\",\"name\":\"PANORAMA HOTEL Heimbuchenthal\",\"url\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.panoramahotel.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/PANO_Logo_500px.png\",\"contentUrl\":\"https:\\\/\\\/www.panoramahotel.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/PANO_Logo_500px.png\",\"width\":500,\"height\":296,\"caption\":\"PANORAMA HOTEL Heimbuchenthal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.panoramahotel.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PANORAMA.Hotel.Heimbuchenthal\",\"https:\\\/\\\/www.instagram.com\\\/panoramahotel_heimbuchenthal\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wellness - PANORAMA Hotel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/","og_locale":"en_US","og_type":"article","og_title":"Wellness - PANORAMA Hotel","og_url":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/","og_site_name":"PANORAMA Hotel","article_publisher":"https:\/\/www.facebook.com\/PANORAMA.Hotel.Heimbuchenthal","article_modified_time":"2025-02-20T08:48:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/","url":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/","name":"Wellness - PANORAMA Hotel","isPartOf":{"@id":"https:\/\/www.panoramahotel.de\/en\/#website"},"datePublished":"2022-01-05T12:57:32+00:00","dateModified":"2025-02-20T08:48:42+00:00","breadcrumb":{"@id":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/wellness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.panoramahotel.de\/en\/"},{"@type":"ListItem","position":2,"name":"Wellness-Intro","item":"https:\/\/www.panoramahotel.de\/en\/wellness-intro\/"},{"@type":"ListItem","position":3,"name":"Wellness"}]},{"@type":"WebSite","@id":"https:\/\/www.panoramahotel.de\/en\/#website","url":"https:\/\/www.panoramahotel.de\/en\/","name":"PANORAMA Hotel","description":"Heimbuchenthal","publisher":{"@id":"https:\/\/www.panoramahotel.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panoramahotel.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.panoramahotel.de\/en\/#organization","name":"PANORAMA HOTEL Heimbuchenthal","url":"https:\/\/www.panoramahotel.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.panoramahotel.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/PANO_Logo_500px.png","contentUrl":"https:\/\/www.panoramahotel.de\/wp-content\/uploads\/2019\/03\/PANO_Logo_500px.png","width":500,"height":296,"caption":"PANORAMA HOTEL Heimbuchenthal"},"image":{"@id":"https:\/\/www.panoramahotel.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PANORAMA.Hotel.Heimbuchenthal","https:\/\/www.instagram.com\/panoramahotel_heimbuchenthal\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/pages\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":0,"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/pages\/1918\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/pages\/1911"}],"wp:attachment":[{"href":"https:\/\/www.panoramahotel.de\/en\/wp-json\/wp\/v2\/media?parent=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}